{"id":57,"date":"2020-06-24T12:33:10","date_gmt":"2020-06-24T09:33:10","guid":{"rendered":"https:\/\/www.baxcom.ro\/?page_id=57"},"modified":"2021-09-27T13:12:07","modified_gmt":"2021-09-27T10:12:07","slug":"portofoliu","status":"publish","type":"page","link":"https:\/\/www.baxcom.ro\/ro\/portofoliu\/","title":{"rendered":"Portofoliu"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"57\" class=\"elementor elementor-57\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-172f8a91 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle elementor-invisible\" data-id=\"172f8a91\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-76416647\" data-id=\"76416647\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ccc8f4 elementor-widget elementor-widget-heading\" data-id=\"4ccc8f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Portofoliu<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-44185cbc elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"44185cbc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-14183d92\" data-id=\"14183d92\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-23573f2 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"23573f2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-62fba2e\" data-id=\"62fba2e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a153da elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1a153da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-cebs-300x225.jpg\" class=\"attachment-medium size-medium wp-image-1202\" alt=\"\" srcset=\"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-cebs-300x225.jpg 300w, https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-cebs.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Centrul Economic Bucovina Suceava <\/h3><p class=\"elementor-image-box-description\">Centru expozi\u0163ional (construc\u0163ie P+2E), parc industrial (8 pavilioane parter), incubator de afaceri (construc\u0163ie P+2E).<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f90265 elementor-align-center translation-block elementor-widget elementor-widget-button\" data-id=\"9f90265\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/www.baxcom.ro\/ro\/portofoliu\/centrul-economic-bucovina-suceava\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">DETALII<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-54520b7\" data-id=\"54520b7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8190a8f elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"8190a8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-pipera-300x225.jpg\" class=\"attachment-medium size-medium wp-image-1207 lazyload\" alt=\"\" data-srcset=\"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-pipera-300x225.jpg 300w, https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-pipera.jpg 640w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Pasaj suprateran Pipera - Barbu V\u0103c\u0103rescu Bucure\u015fti<\/h3><p class=\"elementor-image-box-description\">Lucr\u0103ri de supratraversare a bulevardului Barbu V\u0103c\u0103rescu \u015fi a C\u0103ii Floreasca. Pasajul Pipera are o lungime de aprox. 620 metri.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f8f56c elementor-align-center translation-block elementor-widget elementor-widget-button\" data-id=\"6f8f56c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/www.baxcom.ro\/ro\/portofoliu\/pasaj-suprateran-pipera-barbu-vacarescu-bucuresti\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">DETALII<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-90e6735\" data-id=\"90e6735\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b673975 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"b673975\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-natura-300x225.jpg\" class=\"attachment-medium size-medium wp-image-1206 lazyload\" alt=\"\" data-srcset=\"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-natura-300x225.jpg 300w, https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-natura.jpg 640w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Natura Residence B\u0103neasa Bucure\u015fti<\/h3><p class=\"elementor-image-box-description\">Ansamblul cuprinde opt construc\u0163ii cu regimul de \u00een\u0103l\u0163ime P+2+3E \/ P+2+5E \u015fi subsol general, amenaj\u0103ri exterioare \u015fi \u00eemprejmuiri.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e59a82d elementor-align-center translation-block elementor-widget elementor-widget-button\" data-id=\"e59a82d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/www.baxcom.ro\/ro\/portofoliu\/natura-residence-baneasa-bucuresti\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">DETALII<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e6e92aa elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e6e92aa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-064f2b7\" data-id=\"064f2b7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cda2c3b elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"cda2c3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-lykos-1-300x225.jpg\" class=\"attachment-medium size-medium wp-image-1205 lazyload\" alt=\"\" data-srcset=\"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-lykos-1-300x225.jpg 300w, https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-lykos-1.jpg 640w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Sediul central Inform Lykos Bucure\u015fti<\/h3><p class=\"elementor-image-box-description\">BAXCOM a participat la realizarea construc\u0163iilor Inform Lykos situate \u00een Bucuresti, iar lucr\u0103rile au fost finalizate \u00een anul 2007.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8bfcf1e elementor-align-center translation-block elementor-widget elementor-widget-button\" data-id=\"8bfcf1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/www.baxcom.ro\/ro\/portofoliu\/sediul-central-inform-lykos-bucuresti\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">DETALII<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-16b78b6\" data-id=\"16b78b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ad7b87 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"7ad7b87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-chitila-1-300x225.jpg\" class=\"attachment-medium size-medium wp-image-1203 lazyload\" alt=\"\" data-srcset=\"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-chitila-1-300x225.jpg 300w, https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-chitila-1.jpg 640w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Pasaj suprateran Centur\u0103 Nord Bucure\u015fti-zona Chitila<\/h3><p class=\"elementor-image-box-description\">Pasajul de la Chitila este unul dintre obiectivele de infrastructur\u0103 de pe centura de nord a Bucure\u015ftiului care vor asigura fluidizarea traficului.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9616d08 elementor-align-center translation-block elementor-widget elementor-widget-button\" data-id=\"9616d08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/www.baxcom.ro\/ro\/portofoliu\/pasaj-suprateran-centura-nord-bucuresti-zona-chitila\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">DETALII<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-faf39d8\" data-id=\"faf39d8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d9669e elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"9d9669e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-sighet-300x225.jpg\" class=\"attachment-medium size-medium wp-image-1208 lazyload\" alt=\"\" data-srcset=\"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-sighet-300x225.jpg 300w, https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-sighet.jpg 640w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Reabilitare DN18 Baia Mare - Sighet<\/h3><p class=\"elementor-image-box-description\">BAXCOM a demarat lucr\u0103rile de reabilitare a drumului na\u0163ional DN18 pe tronsonul Baia Mare \u2013 Sighet.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6073b52 elementor-align-center translation-block elementor-widget elementor-widget-button\" data-id=\"6073b52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/www.baxcom.ro\/ro\/portofoliu\/reabilitare-dn18-baia-mare-sighet\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">DETALII<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7f03bb8 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f03bb8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-560d76b\" data-id=\"560d76b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-182d098 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"182d098\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-autostrada-300x225.jpg\" class=\"attachment-medium size-medium wp-image-1199 lazyload\" alt=\"Autostrada Bucure\u015fti - Ploie\u015fti\" data-srcset=\"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-autostrada-300x225.jpg 300w, https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-autostrada.jpg 640w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Autostrada Bucure\u015fti - Ploie\u015fti<\/h3><p class=\"elementor-image-box-description\">Lucr\u0103ri de construc\u0163ie poduri \u015fi pasaje la autostrada Bucure\u015fti - Ploie\u015fti (pod peste r\u00e2ul Prahova, pod peste r\u00e2ul Ialomi\u0163a).<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17b89a1 elementor-align-center translation-block elementor-widget elementor-widget-button\" data-id=\"17b89a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/www.baxcom.ro\/ro\/portofoliu\/autostrada-bucuresti-ploiesti\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">DETALII<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-cad67a2\" data-id=\"cad67a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4f82ee elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"a4f82ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-caransebes-300x225.jpg\" class=\"attachment-medium size-medium wp-image-1201 lazyload\" alt=\"\" data-srcset=\"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-caransebes-300x225.jpg 300w, https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-caransebes.jpg 640w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Reabilitare DN6 Caransebe\u015f<\/h3><p class=\"elementor-image-box-description\">Realizare pere\u0163i de sprijin \u00een beton armat \u015fi rigole ape fluviale pentru protec\u0163ia p\u0103r\u0163ii carosabile din localitatea Doma\u015fnea.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8187bb6 elementor-align-center translation-block elementor-widget elementor-widget-button\" data-id=\"8187bb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/www.baxcom.ro\/ro\/portofoliu\/reabilitare-dn6-caransebes\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">DETALII<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-727ab72\" data-id=\"727ab72\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23f8594 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"23f8594\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-dablerom-300x225.jpg\" class=\"attachment-medium size-medium wp-image-1204 lazyload\" alt=\"\" data-srcset=\"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-dablerom-300x225.jpg 300w, https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-dablerom.jpg 640w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u015eantier V\u00e2lcele Cluj-Napoca<\/h3><p class=\"elementor-image-box-description\">Construc\u0163ia sediului societ\u0103\u0163ii comerciale DABLEROM din localitatea V\u00e2lcele, comuna Feleac, jude\u0163ul Cluj-Napoca.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62ec888 elementor-align-center translation-block elementor-widget elementor-widget-button\" data-id=\"62ec888\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/www.baxcom.ro\/ro\/portofoliu\/santier-valcele-cluj-napoca\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">DETALII<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6440756 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6440756\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-456adc3\" data-id=\"456adc3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5b0c1a elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"b5b0c1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-biserica-300x225.jpg\" class=\"attachment-medium size-medium wp-image-1200 lazyload\" alt=\"\" data-srcset=\"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-biserica-300x225.jpg 300w, https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-biserica.jpg 640w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Biseric\u0103 Marginea Suceava <\/h3><p class=\"elementor-image-box-description\">Construc\u0163ia Bisericii Cultului Penticostal din localitatea Marginea, jude\u0163ul Suceava.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb0ddf1 elementor-align-center translation-block elementor-widget elementor-widget-button\" data-id=\"cb0ddf1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/www.baxcom.ro\/ro\/portofoliu\/biserica-marginea-suceava\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">DETALII<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-60f16f7f\" data-id=\"60f16f7f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74d745a6 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"74d745a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-simeria-300x225.jpg\" class=\"attachment-medium size-medium wp-image-1209 lazyload\" alt=\"\" data-srcset=\"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-simeria-300x225.jpg 300w, https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-simeria.jpg 640w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Reabilitarea liniei de cale ferata Bra\u0219ov-Simeria<\/h3><p class=\"elementor-image-box-description\">Componenta a Coridorului IV Pan European, pentru circulatia trenurilor cu viteza de 160 km\/h.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4267aabf elementor-align-center translation-block elementor-widget elementor-widget-button\" data-id=\"4267aabf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/www.baxcom.ro\/ro\/portofoliu\/reabilitarea-liniei-de-cale-ferata-brasov-simeria\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">DETALII<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-71a7913\" data-id=\"71a7913\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Portofoliu Centrul Economic Bucovina Suceava Centru expozi\u0163ional (construc\u0163ie P+2E), parc industrial (8 pavilioane parter), incubator de afaceri (construc\u0163ie P+2E). DETALII Pasaj suprateran Pipera &#8211; Barbu V\u0103c\u0103rescu Bucure\u015fti Lucr\u0103ri de supratraversare a bulevardului Barbu V\u0103c\u0103rescu \u015fi a C\u0103ii Floreasca. Pasajul Pipera are o lungime de aprox. 620 metri. DETALII Natura Residence B\u0103neasa Bucure\u015fti Ansamblul cuprinde opt [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"iawp_total_views":812,"footnotes":""},"class_list":["post-57","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Portofoliu &#8211; BAXCOM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.baxcom.ro\/ro\/portofoliu\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Portofoliu &#8211; BAXCOM\" \/>\n<meta property=\"og:description\" content=\"Portofoliu Centrul Economic Bucovina Suceava Centru expozi\u0163ional (construc\u0163ie P+2E), parc industrial (8 pavilioane parter), incubator de afaceri (construc\u0163ie P+2E). DETALII Pasaj suprateran Pipera &#8211; Barbu V\u0103c\u0103rescu Bucure\u015fti Lucr\u0103ri de supratraversare a bulevardului Barbu V\u0103c\u0103rescu \u015fi a C\u0103ii Floreasca. Pasajul Pipera are o lungime de aprox. 620 metri. DETALII Natura Residence B\u0103neasa Bucure\u015fti Ansamblul cuprinde opt [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.baxcom.ro\/ro\/portofoliu\/\" \/>\n<meta property=\"og:site_name\" content=\"BAXCOM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Baxcom\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-27T10:12:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-cebs-300x225.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Timp estimat pentru citire\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.baxcom.ro\\\/ro\\\/portofoliu\\\/\",\"url\":\"https:\\\/\\\/www.baxcom.ro\\\/ro\\\/portofoliu\\\/\",\"name\":\"Portofoliu &#8211; BAXCOM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.baxcom.ro\\\/ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.baxcom.ro\\\/ro\\\/portofoliu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.baxcom.ro\\\/ro\\\/portofoliu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.baxcom.ro\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/portofoliu-cebs-300x225.jpg\",\"datePublished\":\"2020-06-24T09:33:10+00:00\",\"dateModified\":\"2021-09-27T10:12:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.baxcom.ro\\\/ro\\\/portofoliu\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.baxcom.ro\\\/ro\\\/portofoliu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/www.baxcom.ro\\\/ro\\\/portofoliu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.baxcom.ro\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/portofoliu-cebs-300x225.jpg\",\"contentUrl\":\"https:\\\/\\\/www.baxcom.ro\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/portofoliu-cebs-300x225.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.baxcom.ro\\\/ro\\\/portofoliu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.baxcom.ro\\\/ro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portofoliu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.baxcom.ro\\\/ro\\\/#website\",\"url\":\"https:\\\/\\\/www.baxcom.ro\\\/ro\\\/\",\"name\":\"BAXCOM\",\"description\":\"Creat\u0103 pentru a construi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.baxcom.ro\\\/ro\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.baxcom.ro\\\/ro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.baxcom.ro\\\/ro\\\/#organization\",\"name\":\"BAXCOM\",\"url\":\"https:\\\/\\\/www.baxcom.ro\\\/ro\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/www.baxcom.ro\\\/ro\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.baxcom.ro\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/BAXCOM-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.baxcom.ro\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/BAXCOM-logo.png\",\"width\":150,\"height\":150,\"caption\":\"BAXCOM\"},\"image\":{\"@id\":\"https:\\\/\\\/www.baxcom.ro\\\/ro\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Baxcom\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Portofoliu &#8211; BAXCOM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.baxcom.ro\/ro\/portofoliu\/","og_locale":"ro_RO","og_type":"article","og_title":"Portofoliu &#8211; BAXCOM","og_description":"Portofoliu Centrul Economic Bucovina Suceava Centru expozi\u0163ional (construc\u0163ie P+2E), parc industrial (8 pavilioane parter), incubator de afaceri (construc\u0163ie P+2E). DETALII Pasaj suprateran Pipera &#8211; Barbu V\u0103c\u0103rescu Bucure\u015fti Lucr\u0103ri de supratraversare a bulevardului Barbu V\u0103c\u0103rescu \u015fi a C\u0103ii Floreasca. Pasajul Pipera are o lungime de aprox. 620 metri. DETALII Natura Residence B\u0103neasa Bucure\u015fti Ansamblul cuprinde opt [&hellip;]","og_url":"https:\/\/www.baxcom.ro\/ro\/portofoliu\/","og_site_name":"BAXCOM","article_publisher":"https:\/\/www.facebook.com\/Baxcom\/","article_modified_time":"2021-09-27T10:12:07+00:00","og_image":[{"url":"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-cebs-300x225.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Timp estimat pentru citire":"4 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.baxcom.ro\/ro\/portofoliu\/","url":"https:\/\/www.baxcom.ro\/ro\/portofoliu\/","name":"Portofoliu &#8211; BAXCOM","isPartOf":{"@id":"https:\/\/www.baxcom.ro\/ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.baxcom.ro\/ro\/portofoliu\/#primaryimage"},"image":{"@id":"https:\/\/www.baxcom.ro\/ro\/portofoliu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-cebs-300x225.jpg","datePublished":"2020-06-24T09:33:10+00:00","dateModified":"2021-09-27T10:12:07+00:00","breadcrumb":{"@id":"https:\/\/www.baxcom.ro\/ro\/portofoliu\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.baxcom.ro\/ro\/portofoliu\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/www.baxcom.ro\/ro\/portofoliu\/#primaryimage","url":"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-cebs-300x225.jpg","contentUrl":"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/portofoliu-cebs-300x225.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.baxcom.ro\/ro\/portofoliu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.baxcom.ro\/ro\/"},{"@type":"ListItem","position":2,"name":"Portofoliu"}]},{"@type":"WebSite","@id":"https:\/\/www.baxcom.ro\/ro\/#website","url":"https:\/\/www.baxcom.ro\/ro\/","name":"BAXCOM","description":"Creat\u0103 pentru a construi","publisher":{"@id":"https:\/\/www.baxcom.ro\/ro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.baxcom.ro\/ro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"},{"@type":"Organization","@id":"https:\/\/www.baxcom.ro\/ro\/#organization","name":"BAXCOM","url":"https:\/\/www.baxcom.ro\/ro\/","logo":{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/www.baxcom.ro\/ro\/#\/schema\/logo\/image\/","url":"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/BAXCOM-logo.png","contentUrl":"https:\/\/www.baxcom.ro\/wp-content\/uploads\/2020\/06\/BAXCOM-logo.png","width":150,"height":150,"caption":"BAXCOM"},"image":{"@id":"https:\/\/www.baxcom.ro\/ro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Baxcom\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.baxcom.ro\/ro\/wp-json\/wp\/v2\/pages\/57","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.baxcom.ro\/ro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.baxcom.ro\/ro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.baxcom.ro\/ro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.baxcom.ro\/ro\/wp-json\/wp\/v2\/comments?post=57"}],"version-history":[{"count":24,"href":"https:\/\/www.baxcom.ro\/ro\/wp-json\/wp\/v2\/pages\/57\/revisions"}],"predecessor-version":[{"id":1487,"href":"https:\/\/www.baxcom.ro\/ro\/wp-json\/wp\/v2\/pages\/57\/revisions\/1487"}],"wp:attachment":[{"href":"https:\/\/www.baxcom.ro\/ro\/wp-json\/wp\/v2\/media?parent=57"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}